{"id":1691,"count":6,"description":"Database","link":"https:\/\/www.ecommerceupdate.com.br\/en_za\/categoria-produto\/livros\/computacao-informatica-e-midias-digitais\/base-de-dados\/","name":"Database","slug":"base-de-dados","taxonomy":"product_cat","parent":1641,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/www.ecommerceupdate.com.br\/en_za\/wp-json\/wp\/v2\/product_cat\/1691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecommerceupdate.com.br\/en_za\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.ecommerceupdate.com.br\/en_za\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecommerceupdate.com.br\/en_za\/wp-json\/wp\/v2\/product_cat\/1641"}],"wp:post_type":[{"href":"https:\/\/www.ecommerceupdate.com.br\/en_za\/wp-json\/wp\/v2\/product?product_cat=1691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}